{"id":30773,"date":"2021-09-28T09:11:00","date_gmt":"2021-09-28T09:11:00","guid":{"rendered":"https:\/\/specialpapers.fedrigoni.com\/resources\/"},"modified":"2025-11-11T11:02:11","modified_gmt":"2025-11-11T11:02:11","slug":"resources","status":"publish","type":"page","link":"https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/","title":{"rendered":"Resources"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-resources.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-30773","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Resources - FLE | Special Papers<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/\" \/>\n<meta property=\"og:locale\" content=\"nl_BE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Resources - FLE | Special Papers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/\" \/>\n<meta property=\"og:site_name\" content=\"Fedrigoni Special Papers\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-11T11:02:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/specialpapers.fedrigoni.com\/wp-content\/uploads\/2021\/09\/Banner-HP-ladder.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ProfilePage\"],\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/resources\\\/\",\"url\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/resources\\\/\",\"name\":\"Resources - FLE | Special Papers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/#website\"},\"datePublished\":\"2021-09-28T09:11:00+00:00\",\"dateModified\":\"2025-11-11T11:02:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/resources\\\/#breadcrumb\"},\"inLanguage\":\"nl-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/resources\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/resources\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Resources\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/#website\",\"url\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/\",\"name\":\"Fedrigoni Special Papers\",\"description\":\"Elevating Creativity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/fle\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-BE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Resources - FLE | Special Papers","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/","og_locale":"nl_BE","og_type":"article","og_title":"Resources - FLE | Special Papers","og_url":"https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/","og_site_name":"Fedrigoni Special Papers","article_modified_time":"2025-11-11T11:02:11+00:00","og_image":[{"width":2200,"height":1467,"url":"https:\/\/specialpapers.fedrigoni.com\/wp-content\/uploads\/2021\/09\/Banner-HP-ladder.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ProfilePage"],"@id":"https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/","url":"https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/","name":"Resources - FLE | Special Papers","isPartOf":{"@id":"https:\/\/specialpapers.fedrigoni.com\/fle\/#website"},"datePublished":"2021-09-28T09:11:00+00:00","dateModified":"2025-11-11T11:02:11+00:00","breadcrumb":{"@id":"https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/#breadcrumb"},"inLanguage":"nl-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/specialpapers.fedrigoni.com\/fle\/resources\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/specialpapers.fedrigoni.com\/fle\/"},{"@type":"ListItem","position":2,"name":"Resources"}]},{"@type":"WebSite","@id":"https:\/\/specialpapers.fedrigoni.com\/fle\/#website","url":"https:\/\/specialpapers.fedrigoni.com\/fle\/","name":"Fedrigoni Special Papers","description":"Elevating Creativity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/specialpapers.fedrigoni.com\/fle\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-BE"}]}},"_links":{"self":[{"href":"https:\/\/specialpapers.fedrigoni.com\/fle\/wp-json\/wp\/v2\/pages\/30773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/specialpapers.fedrigoni.com\/fle\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/specialpapers.fedrigoni.com\/fle\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/specialpapers.fedrigoni.com\/fle\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/specialpapers.fedrigoni.com\/fle\/wp-json\/wp\/v2\/comments?post=30773"}],"version-history":[{"count":0,"href":"https:\/\/specialpapers.fedrigoni.com\/fle\/wp-json\/wp\/v2\/pages\/30773\/revisions"}],"wp:attachment":[{"href":"https:\/\/specialpapers.fedrigoni.com\/fle\/wp-json\/wp\/v2\/media?parent=30773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}