{"id":30978,"date":"2021-08-25T10:33:28","date_gmt":"2021-08-25T10:33:28","guid":{"rendered":"https:\/\/specialpapers.fedrigoni.com\/showcase\/"},"modified":"2021-11-10T09:12:57","modified_gmt":"2021-11-10T09:12:57","slug":"showcase","status":"publish","type":"page","link":"https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/","title":{"rendered":"Showcase"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-showcase.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-30978","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Showcase<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/\" \/>\n<meta property=\"og:locale\" content=\"id_ID\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Showcase\" \/>\n<meta property=\"og:url\" content=\"https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/\" \/>\n<meta property=\"og:site_name\" content=\"Fedrigoni Special Papers\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-10T09:12:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/specialpapers.fedrigoni.com\/wp-content\/uploads\/2021\/09\/Banner-HP-ladder.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ProfilePage\"],\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/showcase\\\/\",\"url\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/showcase\\\/\",\"name\":\"Showcase\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/#website\"},\"datePublished\":\"2021-08-25T10:33:28+00:00\",\"dateModified\":\"2021-11-10T09:12:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/showcase\\\/#breadcrumb\"},\"inLanguage\":\"id\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/showcase\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/showcase\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Showcase\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/#website\",\"url\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/\",\"name\":\"Fedrigoni Special Papers\",\"description\":\"Elevating Creativity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/ind\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"id\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Showcase","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/","og_locale":"id_ID","og_type":"article","og_title":"Showcase","og_url":"https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/","og_site_name":"Fedrigoni Special Papers","article_modified_time":"2021-11-10T09:12:57+00:00","og_image":[{"width":2200,"height":1467,"url":"https:\/\/specialpapers.fedrigoni.com\/wp-content\/uploads\/2021\/09\/Banner-HP-ladder.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ProfilePage"],"@id":"https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/","url":"https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/","name":"Showcase","isPartOf":{"@id":"https:\/\/specialpapers.fedrigoni.com\/ind\/#website"},"datePublished":"2021-08-25T10:33:28+00:00","dateModified":"2021-11-10T09:12:57+00:00","breadcrumb":{"@id":"https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/#breadcrumb"},"inLanguage":"id","potentialAction":[{"@type":"ReadAction","target":["https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/specialpapers.fedrigoni.com\/ind\/showcase\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/specialpapers.fedrigoni.com\/ind\/"},{"@type":"ListItem","position":2,"name":"Showcase"}]},{"@type":"WebSite","@id":"https:\/\/specialpapers.fedrigoni.com\/ind\/#website","url":"https:\/\/specialpapers.fedrigoni.com\/ind\/","name":"Fedrigoni Special Papers","description":"Elevating Creativity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/specialpapers.fedrigoni.com\/ind\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"id"}]}},"_links":{"self":[{"href":"https:\/\/specialpapers.fedrigoni.com\/ind\/wp-json\/wp\/v2\/pages\/30978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/specialpapers.fedrigoni.com\/ind\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/specialpapers.fedrigoni.com\/ind\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/specialpapers.fedrigoni.com\/ind\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/specialpapers.fedrigoni.com\/ind\/wp-json\/wp\/v2\/comments?post=30978"}],"version-history":[{"count":0,"href":"https:\/\/specialpapers.fedrigoni.com\/ind\/wp-json\/wp\/v2\/pages\/30978\/revisions"}],"wp:attachment":[{"href":"https:\/\/specialpapers.fedrigoni.com\/ind\/wp-json\/wp\/v2\/media?parent=30978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}