{"id":45557,"date":"2022-11-24T14:13:49","date_gmt":"2022-11-24T14:13:49","guid":{"rendered":"https:\/\/specialpapers.fedrigoni.com\/vyrobky-z-papiera\/papers\/"},"modified":"2024-07-29T11:06:01","modified_gmt":"2024-07-29T11:06:01","slug":"papiere","status":"publish","type":"page","link":"https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/","title":{"rendered":"Papiere"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":25,"featured_media":0,"parent":44866,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-flexible.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-45557","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Papiere<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/\" \/>\n<meta property=\"og:locale\" content=\"sk_SK\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Papiere\" \/>\n<meta property=\"og:url\" content=\"https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/\" \/>\n<meta property=\"og:site_name\" content=\"Fedrigoni Special Papers\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-29T11:06:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/specialpapers.fedrigoni.com\/wp-content\/uploads\/2021\/09\/Banner-HP-ladder.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2200\" \/>\n\t<meta property=\"og:image:height\" content=\"1467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":[\"WebPage\",\"ProfilePage\"],\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/vyrobky-z-papiera\\\/papiere\\\/\",\"url\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/vyrobky-z-papiera\\\/papiere\\\/\",\"name\":\"Papiere\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/#website\"},\"datePublished\":\"2022-11-24T14:13:49+00:00\",\"dateModified\":\"2024-07-29T11:06:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/vyrobky-z-papiera\\\/papiere\\\/#breadcrumb\"},\"inLanguage\":\"sk-SK\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/vyrobky-z-papiera\\\/papiere\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/vyrobky-z-papiera\\\/papiere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"V\u00fdrobky z papiera\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Papiere\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/#website\",\"url\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/\",\"name\":\"Fedrigoni Special Papers\",\"description\":\"Elevating Creativity\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/specialpapers.fedrigoni.com\\\/svk\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sk-SK\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Papiere","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/","og_locale":"sk_SK","og_type":"article","og_title":"Papiere","og_url":"https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/","og_site_name":"Fedrigoni Special Papers","article_modified_time":"2024-07-29T11:06:01+00:00","og_image":[{"width":2200,"height":1467,"url":"https:\/\/specialpapers.fedrigoni.com\/wp-content\/uploads\/2021\/09\/Banner-HP-ladder.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":["WebPage","ProfilePage"],"@id":"https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/","url":"https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/","name":"Papiere","isPartOf":{"@id":"https:\/\/specialpapers.fedrigoni.com\/svk\/#website"},"datePublished":"2022-11-24T14:13:49+00:00","dateModified":"2024-07-29T11:06:01+00:00","breadcrumb":{"@id":"https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/#breadcrumb"},"inLanguage":"sk-SK","potentialAction":[{"@type":"ReadAction","target":["https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/specialpapers.fedrigoni.com\/svk\/vyrobky-z-papiera\/papiere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/specialpapers.fedrigoni.com\/svk\/"},{"@type":"ListItem","position":2,"name":"V\u00fdrobky z papiera"},{"@type":"ListItem","position":3,"name":"Papiere"}]},{"@type":"WebSite","@id":"https:\/\/specialpapers.fedrigoni.com\/svk\/#website","url":"https:\/\/specialpapers.fedrigoni.com\/svk\/","name":"Fedrigoni Special Papers","description":"Elevating Creativity","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/specialpapers.fedrigoni.com\/svk\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sk-SK"}]}},"_links":{"self":[{"href":"https:\/\/specialpapers.fedrigoni.com\/svk\/wp-json\/wp\/v2\/pages\/45557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/specialpapers.fedrigoni.com\/svk\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/specialpapers.fedrigoni.com\/svk\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/specialpapers.fedrigoni.com\/svk\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/specialpapers.fedrigoni.com\/svk\/wp-json\/wp\/v2\/comments?post=45557"}],"version-history":[{"count":0,"href":"https:\/\/specialpapers.fedrigoni.com\/svk\/wp-json\/wp\/v2\/pages\/45557\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/specialpapers.fedrigoni.com\/svk\/wp-json\/wp\/v2\/pages\/44866"}],"wp:attachment":[{"href":"https:\/\/specialpapers.fedrigoni.com\/svk\/wp-json\/wp\/v2\/media?parent=45557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}